{"id":18200,"date":"2018-04-22T16:43:58","date_gmt":"2018-04-22T20:43:58","guid":{"rendered":"https:\/\/plongeecapitale.com\/?post_type=product&#038;p=18200"},"modified":"2025-06-12T19:03:58","modified_gmt":"2025-06-12T23:03:58","slug":"combo-nitrox-avance-decompression","status":"publish","type":"product","link":"https:\/\/plongeecapitale.com\/en\/produit\/combo-nitrox-avance-decompression\/","title":{"rendered":"Combo: Nitrox avanc\u00e9 &#038; D\u00e9compression"},"content":{"rendered":"<p>Les cours Nitrox avanc\u00e9 et\u00a0proc\u00e9dures\u00a0de d\u00e9compression sont tr\u00e8s souvent enseign\u00e9s conjointement, car les deux\u00a0regroupent plusieurs notions et exercices similaires. De plus une fois parachev\u00e9s ces deux cours se compl\u00e8tent si bien que les possibilit\u00e9s de temps de plong\u00e9e et l\u2019atteinte de profondeur deviennent des donn\u00e9es grandement am\u00e9lior\u00e9es<\/p>\n<p>En joignant \u00a0les deux cours\u00a0vous aurez une meilleure exp\u00e9rience tout en sauvant temps et argent. Ces formations feront de vous des plongeurs mieux entrain\u00e9s et plus s\u00e9curitaires.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les cours Nitrox avanc\u00e9 et\u00a0proc\u00e9dures\u00a0de d\u00e9compression sont tr\u00e8s souvent enseign\u00e9s conjointement, car les deux\u00a0regroupent plusieurs notions et exercices similaires. De plus une fois parachev\u00e9s ces deux cours se compl\u00e8tent si bien que les possibilit\u00e9s de temps de plong\u00e9e et l\u2019atteinte de profondeur deviennent des donn\u00e9es grandement am\u00e9lior\u00e9es En joignant \u00a0les deux cours\u00a0vous aurez une meilleure exp\u00e9rience tout en sauvant temps et argent. Ces formations feront de vous des plongeurs mieux entrain\u00e9s et plus s\u00e9curitaires.<\/p>\n","protected":false},"featured_media":18203,"template":"","meta":[],"product_brand":[],"product_cat":[487,481],"product_tag":[652],"class_list":{"0":"post-18200","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-formations-tech-fr","7":"product_cat-tous_cours","8":"product_tag-cours-tdi-sdi-fr","10":"first","11":"instock","12":"virtual","13":"taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combo: Nitrox avanc\u00e9 &amp; D\u00e9compression - Plong\u00e9e Capitale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combo: Nitrox avanc\u00e9 &amp; D\u00e9compression - Plong\u00e9e Capitale\" \/>\n<meta property=\"og:description\" content=\"Les cours Nitrox avanc\u00e9 et\u00a0proc\u00e9dures\u00a0de d\u00e9compression sont tr\u00e8s souvent enseign\u00e9s conjointement, car les deux\u00a0regroupent plusieurs notions et exercices similaires. De plus une fois parachev\u00e9s ces deux cours se compl\u00e8tent si bien que les possibilit\u00e9s de temps de plong\u00e9e et l\u2019atteinte de profondeur deviennent des donn\u00e9es grandement am\u00e9lior\u00e9es En joignant \u00a0les deux cours\u00a0vous aurez une meilleure exp\u00e9rience tout en sauvant temps et argent. Ces formations feront de vous des plongeurs mieux entrain\u00e9s et plus s\u00e9curitaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/\" \/>\n<meta property=\"og:site_name\" content=\"Plong\u00e9e Capitale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/plongeecapitale\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-12T23:03:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/\",\"url\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/\",\"name\":\"Combo: Nitrox avanc\u00e9 & D\u00e9compression - Plong\u00e9e Capitale\",\"isPartOf\":{\"@id\":\"https:\/\/plongeecapitale.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg\",\"datePublished\":\"2018-04-22T20:43:58+00:00\",\"dateModified\":\"2025-06-12T23:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#primaryimage\",\"url\":\"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg\",\"contentUrl\":\"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/plongeecapitale.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online shop\",\"item\":\"https:\/\/plongeecapitale.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cours &amp; activit\u00e9s\",\"item\":\"https:\/\/plongeecapitale.com\/categorie-produit\/cours-et-activites\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Formations TECH\",\"item\":\"https:\/\/plongeecapitale.com\/categorie-produit\/cours-et-activites\/formations-tech-fr\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Combo: Nitrox avanc\u00e9 &#038; D\u00e9compression\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/plongeecapitale.com\/#website\",\"url\":\"https:\/\/plongeecapitale.com\/\",\"name\":\"Plong\u00e9e Capitale\",\"description\":\"Formations - \u00c9quipements - Boutique en ligne\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/plongeecapitale.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combo: Nitrox avanc\u00e9 & D\u00e9compression - Plong\u00e9e Capitale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/","og_locale":"en_US","og_type":"article","og_title":"Combo: Nitrox avanc\u00e9 & D\u00e9compression - Plong\u00e9e Capitale","og_description":"Les cours Nitrox avanc\u00e9 et\u00a0proc\u00e9dures\u00a0de d\u00e9compression sont tr\u00e8s souvent enseign\u00e9s conjointement, car les deux\u00a0regroupent plusieurs notions et exercices similaires. De plus une fois parachev\u00e9s ces deux cours se compl\u00e8tent si bien que les possibilit\u00e9s de temps de plong\u00e9e et l\u2019atteinte de profondeur deviennent des donn\u00e9es grandement am\u00e9lior\u00e9es En joignant \u00a0les deux cours\u00a0vous aurez une meilleure exp\u00e9rience tout en sauvant temps et argent. Ces formations feront de vous des plongeurs mieux entrain\u00e9s et plus s\u00e9curitaires.","og_url":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/","og_site_name":"Plong\u00e9e Capitale","article_publisher":"https:\/\/www.facebook.com\/plongeecapitale\/","article_modified_time":"2025-06-12T23:03:58+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/","url":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/","name":"Combo: Nitrox avanc\u00e9 & D\u00e9compression - Plong\u00e9e Capitale","isPartOf":{"@id":"https:\/\/plongeecapitale.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#primaryimage"},"image":{"@id":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#primaryimage"},"thumbnailUrl":"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg","datePublished":"2018-04-22T20:43:58+00:00","dateModified":"2025-06-12T23:03:58+00:00","breadcrumb":{"@id":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#primaryimage","url":"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg","contentUrl":"https:\/\/plongeecapitale.com\/wp-content\/uploads\/2019\/04\/cours_AdvNitrox_Deco.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/plongeecapitale.com\/produit\/combo-nitrox-avance-decompression\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/plongeecapitale.com\/en\/"},{"@type":"ListItem","position":2,"name":"Online shop","item":"https:\/\/plongeecapitale.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Cours &amp; activit\u00e9s","item":"https:\/\/plongeecapitale.com\/categorie-produit\/cours-et-activites\/"},{"@type":"ListItem","position":4,"name":"Formations TECH","item":"https:\/\/plongeecapitale.com\/categorie-produit\/cours-et-activites\/formations-tech-fr\/"},{"@type":"ListItem","position":5,"name":"Combo: Nitrox avanc\u00e9 &#038; D\u00e9compression"}]},{"@type":"WebSite","@id":"https:\/\/plongeecapitale.com\/#website","url":"https:\/\/plongeecapitale.com\/","name":"Plong\u00e9e Capitale","description":"Formations - \u00c9quipements - Boutique en ligne","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/plongeecapitale.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/product\/18200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/media\/18203"}],"wp:attachment":[{"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/media?parent=18200"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/product_brand?post=18200"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/product_cat?post=18200"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/plongeecapitale.com\/en\/wp-json\/wp\/v2\/product_tag?post=18200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}